{"id":10100,"date":"2023-05-09T19:30:05","date_gmt":"2023-05-09T17:30:05","guid":{"rendered":"https:\/\/tcolors.net\/produtos\/barniz\/"},"modified":"2026-07-02T12:14:42","modified_gmt":"2026-07-02T10:14:42","slug":"vernizes-e-finais","status":"publish","type":"page","link":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/","title":{"rendered":"Vernizes e Finais"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"portfolio-wrap \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<span class=\"portfolio-loading  none\">   <\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"row portfolio-items masonry-items  \" data-rcp=\"false\" data-masonry-type=\"default\" data-ps=\"9\" data-starting-filter=\"\" data-gutter=\"default\" data-categories-to-show=\"barniz\" data-bypass-cropping=\"true\" data-lightbox-only=\"0\" data-col-num=\"cols-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/pino-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-para-madeira-interior-brilhante-pinho\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz para madeira interior brilhante pinho<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/cerezo-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-para-madeira-interior-brilhante-cerejeira\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz para madeira interior brilhante cerejeira<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/12\/nogal-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-para-madeira-interior-brilhante-nogueira\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz para madeira interior brilhante nogueira<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-brillo-interior-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-brilhante-para-madeira-interior\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz brilhante para madeira interior<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/05\/barniz-mate-interior-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-mate-para-madeira-interior\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz mate para madeira interior<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"#ffffff\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2024\/04\/craquele-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-craquelado-chalky\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz craquelado Chalky<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-mate-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-mate\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz mate<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/05\/vernis-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/verniz-brilhante\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Verniz brilhante<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"#ffffff\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-cera-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/cera-transparente-tcolors-acabamento-vintage-e-protecao-duradoura\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Cera transparente TColors. Acabamento vintage e prote\u00e7\u00e3o duradoura<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3 regular element verniz \"  data-project-cat=\"verniz \" data-default-color=\"true\" data-title-color=\"#ffffff\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size-regular skip-lazy\" src=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate.png\" alt=\"\" height=\"500\" width=\"500\" srcset=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate.png 1000w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-300x300.png 300w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-150x150.png 150w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-768x768.png 768w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-100x100.png 100w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-140x140.png 140w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-500x500.png 500w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-350x350.png 350w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-800x800.png 800w, https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/chalk-vernis_mate-120x120.png 120w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tcolors.net\/pt-pt\/productes\/chalk-paint-verniz\/\"><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Chalk Paint verniz<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/portfolio-->\n\t\t\t<\/div><!--\/portfolio wrap-->\n\t\t\t\n\t\t\t[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;50&#8243; right_padding_desktop=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;menu-productes-families&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;tit-otros-productos&#8221;]\n<h3>Tamb\u00e9m pode conhecer os nossos outros produtos<\/h3>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2055&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/chalk-paint\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/chalk-paint\/\">Chalk Paint<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;10074&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/tinta-acrilica\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/tinta-acrilica\/\">Tinta acr\u00edlica<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2062&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/tempera-preparada\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/tempera-preparada\/\">T\u00eampera preparada<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2053&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/pintura-com-os-dedos\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/pintura-com-os-dedos\/\">Pintura com os dedos<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2059&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/productos\/purpurina\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/purpurina\/\">Purpurina<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2061&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/pintura-textil\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/pintura-textil\/\">Pintura T\u00eaxtil<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8805&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/tinta-blackboard\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/tinta-blackboard\/\">Tinta blackboard<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;2060&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/supertack\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/supertack\/\">Supertack<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8473&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/pasta-sensorial\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/pasta-sensorial\/\">Pasta sensorial<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;menu-productes-familia&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8873&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;https:\/\/tcolors.net\/pt-pt\/produtos\/flyflot\/&#8221; el_class=&#8221;img-productes-familia&#8221;][vc_column_text]\n<h4><a href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/flyflot\/\">Fly &amp; Flot<\/a><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":10071,"menu_order":90,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-10100","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vernizes e Finais - TColors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vernizes e Finais - TColors\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/\" \/>\n<meta property=\"og:site_name\" content=\"TColors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tcolorsoficial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T10:14:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png\" \/>\n\t<meta property=\"og:image:width\" content=\"319\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/vernizes-e-finais\\\/\",\"url\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/vernizes-e-finais\\\/\",\"name\":\"Vernizes e Finais - TColors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#website\"},\"datePublished\":\"2023-05-09T17:30:05+00:00\",\"dateModified\":\"2026-07-02T10:14:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/vernizes-e-finais\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/vernizes-e-finais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/vernizes-e-finais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vernizes e Finais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/\",\"name\":\"TColors\",\"description\":\"Fabricants 100% social de pintures a Espanya\",\"publisher\":{\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#organization\",\"name\":\"TColors\",\"url\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tcolors.net\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/tcolors.png\",\"contentUrl\":\"https:\\\/\\\/tcolors.net\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/tcolors.png\",\"width\":319,\"height\":150,\"caption\":\"TColors\"},\"image\":{\"@id\":\"https:\\\/\\\/tcolors.net\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tcolorsoficial\",\"https:\\\/\\\/www.instagram.com\\\/tcolors_oficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vernizes e Finais - TColors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/","og_locale":"pt_PT","og_type":"article","og_title":"Vernizes e Finais - TColors","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/","og_site_name":"TColors","article_publisher":"https:\/\/www.facebook.com\/tcolorsoficial","article_modified_time":"2026-07-02T10:14:42+00:00","og_image":[{"width":319,"height":150,"url":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/","url":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/","name":"Vernizes e Finais - TColors","isPartOf":{"@id":"https:\/\/tcolors.net\/pt-pt\/#website"},"datePublished":"2023-05-09T17:30:05+00:00","dateModified":"2026-07-02T10:14:42+00:00","breadcrumb":{"@id":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tcolors.net\/pt-pt\/produtos\/vernizes-e-finais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tcolors.net\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/tcolors.net\/pt-pt\/produtos\/"},{"@type":"ListItem","position":3,"name":"Vernizes e Finais"}]},{"@type":"WebSite","@id":"https:\/\/tcolors.net\/pt-pt\/#website","url":"https:\/\/tcolors.net\/pt-pt\/","name":"TColors","description":"Fabricants 100% social de pintures a Espanya","publisher":{"@id":"https:\/\/tcolors.net\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tcolors.net\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/tcolors.net\/pt-pt\/#organization","name":"TColors","url":"https:\/\/tcolors.net\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tcolors.net\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","contentUrl":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","width":319,"height":150,"caption":"TColors"},"image":{"@id":"https:\/\/tcolors.net\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tcolorsoficial","https:\/\/www.instagram.com\/tcolors_oficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/pages\/10100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/comments?post=10100"}],"version-history":[{"count":3,"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/pages\/10100\/revisions"}],"predecessor-version":[{"id":10922,"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/pages\/10100\/revisions\/10922"}],"up":[{"embeddable":true,"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/pages\/10071"}],"wp:attachment":[{"href":"https:\/\/tcolors.net\/pt-pt\/wp-json\/wp\/v2\/media?parent=10100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}