{"id":5263,"date":"2023-04-04T19:29:54","date_gmt":"2023-04-04T17:29:54","guid":{"rendered":"https:\/\/tcolors.net\/quienes-somos\/"},"modified":"2025-10-09T13:33:55","modified_gmt":"2025-10-09T11:33:55","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/tcolors.net\/de\/ueber-uns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom tcolors&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;columna-imatge&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;1785&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;columna-text&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_column_text]\n<h3>Leidenschaft f\u00fcr Farbe, Talent und Transformationswille<\/h3>\n[\/vc_column_text][vc_column_text]\n<h4>TColors ist das Ergebnis der Vereinigung von Leidenschaft f\u00fcr Farbe, professionellem Talent und der Kraft sozialer Ver\u00e4nderung<\/h4>\n[\/vc_column_text][vc_column_text]<strong>TColors<\/strong> ist eine Marke, die vom <strong>Grup Cooperatiu TEB<\/strong> vorangetrieben wird. TEB wurde 1965 mit einer klaren Transformationsvision gegr\u00fcndet. Eine Gruppe von sieben Familien stellte sich eine Welt vor, in der Menschen mit Behinderungen Zugang zu Arbeit und die M\u00f6glichkeit hatten, ein unabh\u00e4ngiges Leben zu f\u00fchren. Mit diesem Ziel gr\u00fcndeten sie die Genossenschaft <strong>TEB<\/strong> im Viertel Barceloneta.<\/p>\n<p>Heute schafft unsere Organisation Arbeitspl\u00e4tze f\u00fcr 800 Menschen mit intellektueller Behinderung und bietet Unterst\u00fctzungsdienste an, damit sie ein unabh\u00e4ngiges Leben f\u00fchren k\u00f6nnen.<\/p>\n<p>Das <strong>TColors<\/strong>-Projekt entstand 1995, als sich das Talent eines spezialisierten kreativen Fachteams f\u00fcr Farbenherstellung mit der Transformationskraft des <strong>Grup Cooperatiu TEB<\/strong> und der Leidenschaft f\u00fcr Farbe vereinte.<\/p>\n<p><strong>&#8222;T&#8220; f\u00fcr Transformation.<\/strong> Bei <strong>TEB<\/strong> setzen wir uns f\u00fcr die Ver\u00e4nderung unserer Umwelt ein, um sie inklusiver, nachhaltiger und vielf\u00e4ltiger zu gestalten. Zu diesem Zweck f\u00f6rdern wir Projekte, die Arbeitspl\u00e4tze schaffen, und bieten Menschen mit Behinderungen Unterst\u00fctzung an, damit sie ihre eigenen Projekte f\u00fcr ein unabh\u00e4ngiges Leben entwickeln k\u00f6nnen.<\/p>\n<p><strong>&#8222;T&#8220; f\u00fcr Talent.<\/strong> Wir glauben an die Menschen und ihr angeborenes Talent, um einen Beitrag zu unserer Gesellschaft zu leisten. Es ist nur notwendig, Arbeitspl\u00e4tze entsprechend anzupassen. Deshalb betonen wir bei TEB gerne, dass wir zu 100% f\u00e4hig sind und dies mit einer anspruchsvollen Qualit\u00e4tsrichtlinie belegen.<\/p>\n<p><strong>Leidenschaft f\u00fcr Farbe.<\/strong> Kunst und Kreativit\u00e4t sind unverzichtbar in unserer Gesellschaft, da sie uns inspirieren, emotional verbinden und uns eine Welt voller M\u00f6glichkeiten vorstellen lassen.<\/p>\n<p>Wenn Sie mehr \u00fcber den Zweck des <strong>Grup Cooperatiu TEB<\/strong> erfahren m\u00f6chten, klicken Sie hier.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom tcolors&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;columna-imatge&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_column_text el_class=&#8220;TEXT_treballador-quisom&#8220;]\n<h4>\u201cMein Name ist Carlos und ich arbeite bei TEB. Ich bin seit 15 Jahren in der Abteilung TColors t\u00e4tig. Ich liebe meine Arbeit, weil ich sehr detailorientiert bin und es mag, die Verpackungsmaschine zu betreuen. Bei TEB unterst\u00fctzen sie mich, damit ich meine Arbeit erledigen kann, und auch bei der Verwirklichung meines Lebensprojekts\u201d.<\/h4>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;columna-text&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;2406&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; el_class=&#8220;foto-treballador-quisom&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;2453&#8243; bg_position=&#8220;right top&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;75&#8243; bottom_padding=&#8220;75&#8243; top_padding_tablet=&#8220;30&#8243; bottom_padding_tablet=&#8220;30&#8243; top_padding_phone=&#8220;15&#8243; bottom_padding_phone=&#8220;15&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; zindex=&#8220;20&#8243; overflow=&#8220;visible&#8220; class=&#8220;inici-valors-SUP&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ff1053&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;50&#8243; bottom_padding=&#8220;50&#8243; top_padding_tablet=&#8220;25&#8243; bottom_padding_tablet=&#8220;25&#8243; top_padding_phone=&#8220;15&#8243; bottom_padding_phone=&#8220;15&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; zindex=&#8220;30&#8243; overflow=&#8220;visible&#8220; class=&#8220;quisom valores&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Unsere Werte<\/h3>\n[\/vc_column_text][vc_column_text]Wir m\u00f6chten Ihnen ein wenig mehr \u00fcber unsere Werte erl\u00e4utern und was uns antreibt, hochwertige Farbe herzustellen, damit Sie sie in Ihren Kreationen genie\u00dfen k\u00f6nnen.[\/vc_column_text][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1834&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;100px&#8220; margin_bottom=&#8220;25&#8243;][vc_column_text]\n<h4 style=\"text-align: center;\">Die Menschen im Mittelpunkt<\/h4>\n[\/vc_column_text][vc_column_text]Wir sind eine Genossenschaft mit sozialer Initiative, die sich den Werten des Genossenschaftswesens verpflichtet f\u00fchlt. Die Menschen stehen im Mittelpunkt unserer Organisation, und wir verf\u00fcgen \u00fcber spezialisierte Teams, die Unterst\u00fctzung bieten, damit Menschen mit Behinderungen Selbstst\u00e4ndigkeit erlangen k\u00f6nnen.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1833&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;100px&#8220; margin_bottom=&#8220;25&#8243;][vc_column_text]\n<h4 style=\"text-align: center;\">F\u00fcr eine nachhaltigere Welt<\/h4>\n[\/vc_column_text][vc_column_text]Wir handeln mit Eifer, um aktiver Teil der Transformation zu einer zug\u00e4nglicheren und nachhaltigeren Gesellschaft zu sein. Deshalb engagieren wir uns f\u00fcr die Ziele f\u00fcr <strong>nachhaltige Entwicklung<\/strong> und setzen Ma\u00dfnahmen zur Energieeinsparung und zur Verbesserung der Zug\u00e4nglichkeit um, unter anderem.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1835&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;100px&#8220; margin_bottom=&#8220;25&#8243;][vc_column_text]\n<h4 style=\"text-align: center;\">Zufriedene Kunden<\/h4>\n[\/vc_column_text][vc_column_text]\n<p class=\"p1\">Wir arbeiten aus Anspruch und Dienstbereitschaft heraus, um die Zufriedenheit unserer Kunden zu erreichen. Neben qualitativ hochwertigen Produkten ist es uns wichtig, dass unsere Kunden eine gute Erfahrung genie\u00dfen. Aus diesem Grund arbeitet unser gesamtes Team, sei es im Labor, in der Produktion oder im Kundenservice, daran, den Bed\u00fcrfnissen vorauszueilen und die Erwartungen zu \u00fcbertreffen.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;2415&#8243; bg_position=&#8220;left bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;65&#8243; bottom_padding=&#8220;65&#8243; top_padding_tablet=&#8220;30&#8243; bottom_padding_tablet=&#8220;30&#8243; top_padding_phone=&#8220;15&#8243; bottom_padding_phone=&#8220;15&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; zindex=&#8220;20&#8243; overflow=&#8220;visible&#8220; class=&#8220;inici-valors-INF&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom cliente&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;2387&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; el_class=&#8220;imatge-annex-quisom&#8220;][vc_column_text el_class=&#8220;text-annex-quisom&#8220;]Das 65% der Energie, die wir f\u00fcr die Herstellung unserer Produkte verwenden, stammt aus erneuerbaren Energien. Unsere Einrichtungen verf\u00fcgen \u00fcber Eigenverbrauch-Solaranlagen, und den Rest der Energie beziehen wir von Energieanbietern, die haupts\u00e4chlich auf erneuerbare Energien setzen.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;2388&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; el_class=&#8220;imatge-annex-quisom&#8220;][vc_column_text el_class=&#8220;text-annex-quisom&#8220;]Wir legen gro\u00dfen Wert auf Sicherheit, daher werden alle unsere Produkte auf Wasserbasis hergestellt und entsprechen der EU-Richtlinie EN-71 f\u00fcr die Sicherheit von Spielzeug. Nicht nur unsere Kinderprodukte, sondern auch unsere Chalk Paint, Acrylfarbe und Lacke sind f\u00fcr den Gebrauch durch Kinder geeignet.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; bottom_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; bottom_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; bottom_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom timeline&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Unsere Geschichte<\/h3>\n[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1697099583233{padding-bottom: 25px !important;}&#8220;]Seit ihren Anf\u00e4ngen in den 60er Jahren hat sich die <strong>Grup Cooperatiu TEB<\/strong> weiterentwickelt, indem sie Ausbildung mit Arbeit verbindet, um eine vollst\u00e4ndige Inklusion zu erreichen.[\/vc_column_text]<div class=\"jstime timeline_preloader\" style=\"opacity:0;width:35px;margin:auto;margin-top:30px;\"><img decoding=\"async\" style=\"box-shadow:none;\" alt=\"timeline_pre_loader\" src=\"https:\/\/tcolors.net\/wp-content\/plugins\/Ultimate_VC_Addons\/modules\/..\/assets\/img\/timeline_pre-loader.gif\" \/><\/div><div class=\"smile-icon-timeline-wrap jstime   \"   data-time_block_bg_color=&quot;#ffffff&quot;  style=\"opacity:0; \"><div class=\"timeline-line \" style=\"border-right-color:#c4007a;\"><span><\/span><\/div><div class=\"timeline-wrapper\"><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-2682\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-2682 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2025<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-2682 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Wir nehmen an den Messen <strong>FISOP<\/strong> und <strong>FORUM DSG<\/strong> (Schreibwaren), <strong>Expocadena<\/strong> (Ehlis) und <strong>Profer Fair<\/strong> (Coferdroza) teil. Wir waren auch auf der <strong>Expo Papeler\u00eda Canaria<\/strong> vertreten.<\/p>\n<p>Wir haben unsere Pr\u00e4senz in den Leroy Merlin Filialen ausgebaut und neue Verkaufsstellen in Alicante, Burjassot und Cartagena er\u00f6ffnet.<\/p>\n<p>Wir sind mit der Kampagne &#8222;Back to school + solidarity&#8220; ins Bauhaus eingestiegen, die in den 12 Filialen pr\u00e4sent ist.<\/p>\n<p>Wir haben Einlegesohlen mit Coferdroza und Neopro signiert und eine verkaufsfertige Packung mit Acrylfarben und Textilien zusammengestellt, um die Implementierung im Gesch\u00e4ft zu erleichtern.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-6037\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-6037 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2023<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-6037 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Wir haben unsere neue Website gestartet und unsere Pr\u00e4senz auf Messen erh\u00f6ht, indem wir am <strong>Handmade Festival of Barcelona<\/strong> teilgenommen haben, mit einem Angebot an kreativen Workshops, die sich an der <em>Do It Yourself<\/em> (DIY)-Bewegung orientieren, einer Lebensphilosophie, die die transformative und kreative Kapazit\u00e4t der Menschen f\u00f6rdert.<\/p>\n<p>Wir arbeiten auch mit <strong>FISOP<\/strong> und <strong>FORUM DSG<\/strong> (Schreibwaren) zusammen, um unsere Pr\u00e4senz in der Branche zu verst\u00e4rken.<\/p>\n<p>Dar\u00fcber hinaus positionierten wir Produkte in der physischen Leroy Merlin Filiale in Gij\u00f3n und f\u00fchrten in 55 Leroy Merlin Filialen im ganzen Land Workshops f\u00fcr Kinder zum Schulanfang durch.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-1969\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-1969 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2023<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-1969 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Wir sind auf dem <strong>Handmade Festival in Barcelona<\/strong> vertreten, mit einem Angebot an kreativen Workshops, die sich mit der Do-it-Yourself-Bewegung verbinden, einer Lebensphilosophie, die die transformative und kreative F\u00e4higkeit der Menschen f\u00f6rdert.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-8737\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-8737 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2022<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-8737 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Wir traten in den <strong>Leroy Merlin-Marktplatz<\/strong> ein und waren die erste gro\u00dfe Vertriebsgruppe, die auf unser soziales Projekt setzte und uns ihre T\u00fcren \u00f6ffnete. Wir haben zum ersten Mal an den Messen <strong>FISOP<\/strong> (Schreibwarengesch\u00e4fte) und <strong>EUROBRICO<\/strong> (DIY) teilgenommen, dank der Unterst\u00fctzung der Feria Valencia.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-9139\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-9139 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2021<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-9139 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><strong>TColors<\/strong> \u00e4ndert seinen Standort, um den Service zu verbessern. Die neuen Einrichtungen erm\u00f6glichen eine effizientere Arbeit und verf\u00fcgen \u00fcber ein modernes Labor zur Verbesserung des Designs und des Qualit\u00e4tsmanagements. Es wurden auch Verbesserungen bei der Barrierefreiheit eingef\u00fchrt, um die Unterst\u00fctzung von Menschen mit Behinderungen zu erleichtern.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-7674\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-7674 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2015<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-7674 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><strong>TColors<\/strong> nimmt zum ersten Mal an der internationalen Messe <strong>Creative World in Frankfurt<\/strong> teil. Damit wird <strong>TColors<\/strong> zu einer internationalen Marke, die Kunden in Portugal, Frankreich, Griechenland, Polen, Litauen und Italien bedient.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-1125\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-1125 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2013<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-1125 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Neustart der Marke <strong>TColors<\/strong> mit einem erneuerten Katalog. Das Produktsortiment wurde erweitert, um das Erlebnis zu verbessern, dank einer Vielzahl von Farbt\u00f6nen und Bastelfarben.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-1573\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-1573 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2009<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-1573 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Verlagerung der Fabrik in die Einrichtungen des <strong>TEB<\/strong> und Integration von Menschen mit Behinderungen in die Produktion.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-8135\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-8135 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">2007<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-8135 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Verlagerung der Fabrik in die Einrichtungen des <strong>TEB<\/strong> und Integration von Menschen mit Behinderungen in die Produktion.<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-7851\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-7851 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">1995<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-7851 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Das Projekt <strong>TColors<\/strong> wird geboren.<\/div><\/div> <!-- header --><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom tcolors&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5263","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber uns - TColors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tcolors.net\/de\/ueber-uns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns - TColors\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom tcolors&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tcolors.net\/de\/ueber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"TColors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tcolorsoficial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T11:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png\" \/>\n\t<meta property=\"og:image:width\" content=\"319\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tcolors.net\/de\/ueber-uns\/\",\"url\":\"https:\/\/tcolors.net\/de\/ueber-uns\/\",\"name\":\"\u00dcber uns - TColors\",\"isPartOf\":{\"@id\":\"https:\/\/tcolors.net\/de\/#website\"},\"datePublished\":\"2023-04-04T17:29:54+00:00\",\"dateModified\":\"2025-10-09T11:33:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tcolors.net\/de\/ueber-uns\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tcolors.net\/de\/ueber-uns\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tcolors.net\/de\/ueber-uns\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tcolors.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tcolors.net\/de\/#website\",\"url\":\"https:\/\/tcolors.net\/de\/\",\"name\":\"TColors\",\"description\":\"Fabricants 100% social de pintures a Espanya\",\"publisher\":{\"@id\":\"https:\/\/tcolors.net\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tcolors.net\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tcolors.net\/de\/#organization\",\"name\":\"TColors\",\"url\":\"https:\/\/tcolors.net\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tcolors.net\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png\",\"contentUrl\":\"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png\",\"width\":319,\"height\":150,\"caption\":\"TColors\"},\"image\":{\"@id\":\"https:\/\/tcolors.net\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tcolorsoficial\",\"https:\/\/www.instagram.com\/tcolors_oficial\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcber uns - TColors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tcolors.net\/de\/ueber-uns\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcber uns - TColors","og_description":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_margin=&#8220;100&#8243; top_margin_tablet=&#8220;65&#8243; top_margin_phone=&#8220;40&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;quisom tcolors&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;...","og_url":"https:\/\/tcolors.net\/de\/ueber-uns\/","og_site_name":"TColors","article_publisher":"https:\/\/www.facebook.com\/tcolorsoficial","article_modified_time":"2025-10-09T11:33:55+00:00","og_image":[{"width":319,"height":150,"url":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tcolors.net\/de\/ueber-uns\/","url":"https:\/\/tcolors.net\/de\/ueber-uns\/","name":"\u00dcber uns - TColors","isPartOf":{"@id":"https:\/\/tcolors.net\/de\/#website"},"datePublished":"2023-04-04T17:29:54+00:00","dateModified":"2025-10-09T11:33:55+00:00","breadcrumb":{"@id":"https:\/\/tcolors.net\/de\/ueber-uns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tcolors.net\/de\/ueber-uns\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tcolors.net\/de\/ueber-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tcolors.net\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/tcolors.net\/de\/#website","url":"https:\/\/tcolors.net\/de\/","name":"TColors","description":"Fabricants 100% social de pintures a Espanya","publisher":{"@id":"https:\/\/tcolors.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tcolors.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tcolors.net\/de\/#organization","name":"TColors","url":"https:\/\/tcolors.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tcolors.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","contentUrl":"https:\/\/tcolors.net\/wp-content\/uploads\/2023\/04\/tcolors.png","width":319,"height":150,"caption":"TColors"},"image":{"@id":"https:\/\/tcolors.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tcolorsoficial","https:\/\/www.instagram.com\/tcolors_oficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/pages\/5263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/comments?post=5263"}],"version-history":[{"count":4,"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/pages\/5263\/revisions"}],"predecessor-version":[{"id":8762,"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/pages\/5263\/revisions\/8762"}],"wp:attachment":[{"href":"https:\/\/tcolors.net\/de\/wp-json\/wp\/v2\/media?parent=5263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}